{"id":1511,"date":"2023-12-15T16:23:33","date_gmt":"2023-12-15T15:23:33","guid":{"rendered":"https:\/\/millefeuillemockup.com\/product\/mllfll-021-en\/"},"modified":"2024-11-27T11:33:03","modified_gmt":"2024-11-27T10:33:03","slug":"mllfll-021-en","status":"publish","type":"product","link":"https:\/\/millefeuillemockup.com\/en\/product\/mllfll-021-en\/","title":{"rendered":"MLLFLL-021"},"content":{"rendered":"<p>A minimalist business card mockup, in European format, placed on a Macbook Pro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A minimalist business card mockup, in European format, placed on a Macbook Pro.<\/p>\n","protected":false},"featured_media":986,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[68],"product_tag":[92],"class_list":{"0":"post-1511","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-business-cards-mockup-en","7":"product_tag-mockup-only","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-variable","15":"has-default-attributes"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MLLFLL-021 | Millefeuille Mockup<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/millefeuillemockup.com\/en\/product\/mllfll-021-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MLLFLL-021 | Millefeuille Mockup\" \/>\n<meta property=\"og:description\" content=\"A minimalist business card mockup, in European format, placed on a Macbook Pro.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/millefeuillemockup.com\/en\/product\/mllfll-021-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Millefeuille Mockup\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-27T10:33:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/millefeuillemockup.com\/wp-content\/uploads\/2023\/05\/MLLFLL-021-millefeuille-mockup-antoine-peltier.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@antoinepeltier_\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/millefeuillemockup.com\\\/en\\\/product\\\/mllfll-021-en\\\/\",\"url\":\"https:\\\/\\\/millefeuillemockup.com\\\/en\\\/product\\\/mllfll-021-en\\\/\",\"name\":\"MLLFLL-021 | Millefeuille Mockup\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/millefeuillemockup.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/millefeuillemockup.com\\\/en\\\/product\\\/mllfll-021-en\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/millefeuillemockup.com\\\/en\\\/product\\\/mllfll-021-en\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/millefeuillemockup.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/MLLFLL-021-millefeuille-mockup-antoine-peltier.jpeg\",\"datePublished\":\"2023-12-15T15:23:33+00:00\",\"dateModified\":\"2024-11-27T10:33:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/millefeuillemockup.com\\\/en\\\/product\\\/mllfll-021-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/millefeuillemockup.com\\\/en\\\/product\\\/mllfll-021-en\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/millefeuillemockup.com\\\/en\\\/product\\\/mllfll-021-en\\\/#primaryimage\",\"url\":\"https:\\\/\\\/millefeuillemockup.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/MLLFLL-021-millefeuille-mockup-antoine-peltier.jpeg\",\"contentUrl\":\"https:\\\/\\\/millefeuillemockup.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/MLLFLL-021-millefeuille-mockup-antoine-peltier.jpeg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/millefeuillemockup.com\\\/en\\\/product\\\/mllfll-021-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/millefeuillemockup.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/millefeuillemockup.com\\\/en\\\/shop-real-mockups\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MLLFLL-021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/millefeuillemockup.com\\\/#website\",\"url\":\"https:\\\/\\\/millefeuillemockup.com\\\/\",\"name\":\"Millefeuille Mockup\",\"description\":\"Millefeuille Mockup aide les designers \u00e0 mieux vendre leurs id\u00e9es\",\"publisher\":{\"@id\":\"https:\\\/\\\/millefeuillemockup.com\\\/#organization\"},\"alternateName\":\"MLLFLL\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/millefeuillemockup.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/millefeuillemockup.com\\\/#organization\",\"name\":\"Millefeuille Mockup\",\"alternateName\":\"MLLFLL\",\"url\":\"https:\\\/\\\/millefeuillemockup.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/millefeuillemockup.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/millefeuillemockup.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/LOGO-CARRE-1.jpg\",\"contentUrl\":\"https:\\\/\\\/millefeuillemockup.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/LOGO-CARRE-1.jpg\",\"width\":580,\"height\":580,\"caption\":\"Millefeuille Mockup\"},\"image\":{\"@id\":\"https:\\\/\\\/millefeuillemockup.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/antoinepeltier_\",\"https:\\\/\\\/www.instagram.com\\\/millefeuillemockup\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MLLFLL-021 | Millefeuille Mockup","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/millefeuillemockup.com\/en\/product\/mllfll-021-en\/","og_locale":"en_US","og_type":"article","og_title":"MLLFLL-021 | Millefeuille Mockup","og_description":"A minimalist business card mockup, in European format, placed on a Macbook Pro.","og_url":"https:\/\/millefeuillemockup.com\/en\/product\/mllfll-021-en\/","og_site_name":"Millefeuille Mockup","article_modified_time":"2024-11-27T10:33:03+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/millefeuillemockup.com\/wp-content\/uploads\/2023\/05\/MLLFLL-021-millefeuille-mockup-antoine-peltier.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@antoinepeltier_","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/millefeuillemockup.com\/en\/product\/mllfll-021-en\/","url":"https:\/\/millefeuillemockup.com\/en\/product\/mllfll-021-en\/","name":"MLLFLL-021 | Millefeuille Mockup","isPartOf":{"@id":"https:\/\/millefeuillemockup.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/millefeuillemockup.com\/en\/product\/mllfll-021-en\/#primaryimage"},"image":{"@id":"https:\/\/millefeuillemockup.com\/en\/product\/mllfll-021-en\/#primaryimage"},"thumbnailUrl":"https:\/\/millefeuillemockup.com\/wp-content\/uploads\/2023\/05\/MLLFLL-021-millefeuille-mockup-antoine-peltier.jpeg","datePublished":"2023-12-15T15:23:33+00:00","dateModified":"2024-11-27T10:33:03+00:00","breadcrumb":{"@id":"https:\/\/millefeuillemockup.com\/en\/product\/mllfll-021-en\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/millefeuillemockup.com\/en\/product\/mllfll-021-en\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/millefeuillemockup.com\/en\/product\/mllfll-021-en\/#primaryimage","url":"https:\/\/millefeuillemockup.com\/wp-content\/uploads\/2023\/05\/MLLFLL-021-millefeuille-mockup-antoine-peltier.jpeg","contentUrl":"https:\/\/millefeuillemockup.com\/wp-content\/uploads\/2023\/05\/MLLFLL-021-millefeuille-mockup-antoine-peltier.jpeg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/millefeuillemockup.com\/en\/product\/mllfll-021-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/millefeuillemockup.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/millefeuillemockup.com\/en\/shop-real-mockups\/"},{"@type":"ListItem","position":3,"name":"MLLFLL-021"}]},{"@type":"WebSite","@id":"https:\/\/millefeuillemockup.com\/#website","url":"https:\/\/millefeuillemockup.com\/","name":"Millefeuille Mockup","description":"Millefeuille Mockup aide les designers \u00e0 mieux vendre leurs id\u00e9es","publisher":{"@id":"https:\/\/millefeuillemockup.com\/#organization"},"alternateName":"MLLFLL","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/millefeuillemockup.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/millefeuillemockup.com\/#organization","name":"Millefeuille Mockup","alternateName":"MLLFLL","url":"https:\/\/millefeuillemockup.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/millefeuillemockup.com\/#\/schema\/logo\/image\/","url":"https:\/\/millefeuillemockup.com\/wp-content\/uploads\/2023\/08\/LOGO-CARRE-1.jpg","contentUrl":"https:\/\/millefeuillemockup.com\/wp-content\/uploads\/2023\/08\/LOGO-CARRE-1.jpg","width":580,"height":580,"caption":"Millefeuille Mockup"},"image":{"@id":"https:\/\/millefeuillemockup.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/antoinepeltier_","https:\/\/www.instagram.com\/millefeuillemockup\/"]}]}},"_links":{"self":[{"href":"https:\/\/millefeuillemockup.com\/en\/wp-json\/wp\/v2\/product\/1511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/millefeuillemockup.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/millefeuillemockup.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/millefeuillemockup.com\/en\/wp-json\/wp\/v2\/media\/986"}],"wp:attachment":[{"href":"https:\/\/millefeuillemockup.com\/en\/wp-json\/wp\/v2\/media?parent=1511"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/millefeuillemockup.com\/en\/wp-json\/wp\/v2\/product_brand?post=1511"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/millefeuillemockup.com\/en\/wp-json\/wp\/v2\/product_cat?post=1511"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/millefeuillemockup.com\/en\/wp-json\/wp\/v2\/product_tag?post=1511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}